{"id":434,"count":1,"description":"","link":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/","name":"Bangkok Design Week 2024","slug":"bangkok-design-week-2024","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bangkok Design Week 2024 Archives - TheReporterAsia\/eng<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bangkok Design Week 2024 Archives - TheReporterAsia\/eng\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"TheReporterAsia\/eng\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/tag\\\/bangkok-design-week-2024\\\/\",\"url\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/tag\\\/bangkok-design-week-2024\\\/\",\"name\":\"Bangkok Design Week 2024 Archives - TheReporterAsia\\\/eng\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/tag\\\/bangkok-design-week-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/tag\\\/bangkok-design-week-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bangkok Design Week 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/\",\"name\":\"TheReporterAsia\\\/eng\",\"description\":\"The all economy news in ASIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/#organization\",\"name\":\"TheReporterAsia\\\/eng\",\"url\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/THEREPORTER_logo_274x90.png\",\"contentUrl\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/THEREPORTER_logo_274x90.png\",\"width\":274,\"height\":90,\"caption\":\"TheReporterAsia\\\/eng\"},\"image\":{\"@id\":\"https:\\\/\\\/thereporter.asia\\\/eng\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thereporter.asia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bangkok Design Week 2024 Archives - TheReporterAsia\/eng","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/","og_locale":"en_US","og_type":"article","og_title":"Bangkok Design Week 2024 Archives - TheReporterAsia\/eng","og_url":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/","og_site_name":"TheReporterAsia\/eng","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/","url":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/","name":"Bangkok Design Week 2024 Archives - TheReporterAsia\/eng","isPartOf":{"@id":"https:\/\/thereporter.asia\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thereporter.asia\/eng\/tag\/bangkok-design-week-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thereporter.asia\/eng\/"},{"@type":"ListItem","position":2,"name":"Bangkok Design Week 2024"}]},{"@type":"WebSite","@id":"https:\/\/thereporter.asia\/eng\/#website","url":"https:\/\/thereporter.asia\/eng\/","name":"TheReporterAsia\/eng","description":"The all economy news in ASIA","publisher":{"@id":"https:\/\/thereporter.asia\/eng\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thereporter.asia\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/thereporter.asia\/eng\/#organization","name":"TheReporterAsia\/eng","url":"https:\/\/thereporter.asia\/eng\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thereporter.asia\/eng\/#\/schema\/logo\/image\/","url":"https:\/\/thereporter.asia\/eng\/wp-content\/uploads\/2023\/10\/THEREPORTER_logo_274x90.png","contentUrl":"https:\/\/thereporter.asia\/eng\/wp-content\/uploads\/2023\/10\/THEREPORTER_logo_274x90.png","width":274,"height":90,"caption":"TheReporterAsia\/eng"},"image":{"@id":"https:\/\/thereporter.asia\/eng\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thereporter.asia"]}]}},"_links":{"self":[{"href":"https:\/\/thereporter.asia\/eng\/wp-json\/wp\/v2\/tags\/434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thereporter.asia\/eng\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thereporter.asia\/eng\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thereporter.asia\/eng\/wp-json\/wp\/v2\/posts?tags=434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}